{"id":13877,"date":"2019-11-05T10:08:44","date_gmt":"2019-11-05T10:08:44","guid":{"rendered":"https:\/\/3d4kids.eu\/private_provider\/printe3d-lv\/"},"modified":"2019-11-05T10:08:44","modified_gmt":"2019-11-05T10:08:44","slug":"printe3d-lv","status":"publish","type":"private_provider","link":"https:\/\/www.3d4kids.eu\/sl\/private_provider\/printe3d-lv\/","title":{"rendered":"Printe3D.LV"},"template":"","class_list":["post-13877","private_provider","type-private_provider","status-publish","hentry"],"acf":{"description":"3D printer store. We also offer 3D modeling services and 3D model printing.","main_service":"Consumables services","secondary_service":"Hardware products","city":"Riga","country":"Latvia","logo_url":"https:\/\/3d4kids.eu\/wp-content\/uploads\/2019\/11\/3D4KIDS-Providers-Template-SSOM36_Printe3D_LV.png","website":"https:\/\/www.printe3d.lv\/en\/","email":""},"_links":{"self":[{"href":"https:\/\/www.3d4kids.eu\/sl\/wp-json\/wp\/v2\/private_provider\/13877\/"}],"collection":[{"href":"https:\/\/www.3d4kids.eu\/sl\/wp-json\/wp\/v2\/private_provider\/"}],"about":[{"href":"https:\/\/www.3d4kids.eu\/sl\/wp-json\/wp\/v2\/types\/private_provider\/"}],"wp:attachment":[{"href":"https:\/\/www.3d4kids.eu\/sl\/wp-json\/wp\/v2\/media\/?parent=13877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}